{"id":35703,"date":"2025-04-16T18:06:40","date_gmt":"2025-04-16T21:06:40","guid":{"rendered":"https:\/\/acrj.org.br\/?p=35703"},"modified":"2025-04-28T16:19:43","modified_gmt":"2025-04-28T19:19:43","slug":"reuniao-debate-os-projetos-em-andamento-e-apresenta-novo-vice-do-conselho","status":"publish","type":"post","link":"https:\/\/acrj.org.br\/index.php\/2025\/04\/16\/reuniao-debate-os-projetos-em-andamento-e-apresenta-novo-vice-do-conselho\/","title":{"rendered":"Reuni\u00e3o aborda os projetos em andamento e apresenta novo Vice do Conselho"},"content":{"rendered":"\n<p>O Conselho Empresarial do Desenvolvimento do Mercado e Capitais da ACRJ (Codemec), se reuniu, dia 16 de abril, para apresentar o novo vice-presidente do Conselho, Marcos Oscar Tisser, e debater os projetos em andamento. Marcos Tisser, tem mais de 30 anos de experi\u00eancia no sistema financeiro, com Apimec, com passagens pelo Banco do Brasil, Previ, BB Asset, e foi um dos criadores da Sociedade Operadora do Mercado de Acesso (SOMA), com atua\u00e7\u00e3o comercial que viabilizou a listagem de diversas empresas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-thumbnail\"><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2025\/04\/1000109778-150x150.png\" alt=\"\" class=\"wp-image-35707\"\/><figcaption class=\"wp-element-caption\"><em>Marcos Oscar Tisser<\/em><\/figcaption><\/figure>\n\n\n\n<p>O presidente do Conselho, Luiz Guilherme Dias, apresentou os projetos em andamento e os grupos de trabalho que v\u00e3o coorden\u00e1-los.<\/p>\n\n\n\n<p>S\u00e3o eles:<\/p>\n\n\n\n<p><strong>Reativa\u00e7\u00e3o do Centro do Rio<\/strong>, que vai propor \u00e0s entidades p\u00fablicas, privadas e do 3\u00ba setor medidas para revitaliza\u00e7\u00e3o do Centro da Cidade do Rio. Para viabilizar este projeto, Luiz Guilherme adiantou que ser\u00e1 feita uma integra\u00e7\u00e3o com o Conselho de Renova\u00e7\u00e3o do Centro do Rio da ACRJ (GT 1- Abelardo Puccini, Jacyra Lucas, Luiz Guilherme).<\/p>\n\n\n\n<p><strong>Programa de Capacita\u00e7\u00e3o de Companhias de Menor Porte (CMPs)<\/strong>, cujo ante-projeto est\u00e1 em fase de elabora\u00e7\u00e3o e vai trabalhar em parceria com o Conselho de PMEs da ACRJ. De acordo com Luiz Guilherme, a 1\u00aa turma dever\u00e1 ter de 50 a 100 micro e pequenos empres\u00e1rios Associados da ACRJ. (GT 2 &#8211; Marcos Tisser, Enrico Rodrigues, Fernanda Gon\u00e7alves, Luiz Guilherme)<\/p>\n\n\n\n<p><strong>Fundo F\u00e1cil de Investimentos (FFI)<\/strong>, proposta para ANBIMA\/CVM com capitaliza\u00e7\u00e3o por meio de um Fundo com regras do FACIL\/CVM e oportunidade para Companhias de Menor Porte (CMP). (GT 3 &#8211; Joaquim S. Barbosa, Alvaro Bandeira, Ruy Flaks Schneider, Luiz Guilherme)<\/p>\n\n\n\n<p><strong>Banco de Dados e Estat\u00edsticas <\/strong>sobre Empresas do Estado do RJ com estat\u00edsticas trimestrais de \u00edndices de sondagem das condi\u00e7\u00f5es econ\u00f4mico-financeiras das empresas da regi\u00e3o, partir de dados p\u00fablicos da cidade e do estado. ( GT 6 &#8211; Claudio Contador, Marcos Tisser, Luiz Guilherme)<\/p>\n\n\n\n<p>Al\u00e9m disso, o presidente confirmou a realiza\u00e7\u00e3o dos semin\u00e1rios \u201cMercado de Capitais: o motor do crescimento social e econ\u00f4mico\u201d e \u201cFraudes do Mercado\u201d, em junho e julho. ( GTs 4 e 5 &#8211; Luiz Guilherme, Marcos Tisser)<\/p>\n\n\n\n<p>Finalizando o planejamento, foram apresentados os projetos futuros como a realiza\u00e7\u00e3o de Semin\u00e1rios, entre Agosto e Nov\/2025, o Rio Investors Day 2025, em Setembro\/2025, a inaugura\u00e7\u00e3o da Nova Bolsa, em Novembro\/2025 e as discuss\u00f5es sobre o Plano de A\u00e7\u00e3o para 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Empresarial do Desenvolvimento do Mercado e Capitais da ACRJ (Codemec), se reuniu, dia 16 de abril, para apresentar o novo vice-presidente do Conselho,&hellip;<\/p>\n","protected":false},"author":3,"featured_media":35704,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[56,10],"tags":[],"class_list":["post-35703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque_conselhos","category-noticias"],"_links":{"self":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/posts\/35703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=35703"}],"version-history":[{"count":0,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/posts\/35703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/media\/35704"}],"wp:attachment":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=35703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=35703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=35703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}