{"id":29393,"date":"2024-08-01T18:51:16","date_gmt":"2024-08-01T21:51:16","guid":{"rendered":"https:\/\/acrj.org.br\/?p=29393"},"modified":"2025-09-16T15:11:09","modified_gmt":"2025-09-16T18:11:09","slug":"presidente-da-cvm-participa-de-reuniao-do-conselho-do-desenvolvimento-do-mercado-de-capitais-da-acrj","status":"publish","type":"post","link":"https:\/\/acrj.org.br\/index.php\/2024\/08\/01\/presidente-da-cvm-participa-de-reuniao-do-conselho-do-desenvolvimento-do-mercado-de-capitais-da-acrj\/","title":{"rendered":"Presidente da CVM participa de reuni\u00e3o do Conselho do Desenvolvimento do Mercado de Capitais da ACRJ"},"content":{"rendered":"\n<p>O presidente da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), Jo\u00e3o Pedro Nascimento, participou, dia 1\u00ba de agosto, de um encontro promovido pelo Conselho Empresarial do Desenvolvimento do Mercado de Capitais da ACRJ. Jo\u00e3o Pedro Nascimento foi recebido pelo presidente da ACRJ, Josier Vilar, e pelo presidente do Conselho, Thomas Tosta de S\u00e1, e o vice, Luiz Guilherme Dias.<\/p>\n\n\n\n<p>O presidente da CVM comentou sobre a hist\u00f3ria da participa\u00e7\u00e3o do Rio de Janeiro no Mercado de Capitais, reunindo os principais bancos e a boa parte das grandes companhias abertas brasileiras. \u201cO Rio sempre reuniu importantes companhias abertas, fundos de investimentos, bancos e demais agentes de mercado\u201d, disse. Ele lembrou, ainda, que a cidade, assim como diversas regi\u00f5es do Brasil, continua sendo um importante polo de participantes do Mercado de Capitais para projetos e oportunidades.<\/p>\n\n\n\n<p>Sobre a cria\u00e7\u00e3o da nova Bolsa de Valores do Rio, explicou que n\u00e3o cabe ao presidente da CVM antecipar nenhuma an\u00e1lise de m\u00e9rito sobre os pedidos formulados pelos postulantes a novas infraestruturas de mercado. \u201cA CVM est\u00e1 acompanhando tudo com muita prud\u00eancia e de maneira t\u00e9cnica\u201d, sinalizou. O presidente da CVM antecipou que observa, de forma positiva, os interesses de novos agentes de mercado em desenvolverem bolsas de valores e infraestruturas de mercado regulados de valores mobili\u00e1rios como uma demonstra\u00e7\u00e3o da for\u00e7a do Mercado de Capitais do Brasil.<\/p>\n\n\n\n<p>Jo\u00e3o Pedro Nascimento elogiou a iniciativa da ACRJ de criar o Conselho Empresarial de Desenvolvimento do Mercado de Capitais e sugeriu \u00e0 ACRJ uma an\u00e1lise de dados relacionada aos agentes de mercado, com foco em potencial elabora\u00e7\u00e3o de uma amostragem do percentual das corretoras, dos assessores de investimentos e das companhias abertas sediados no Rio de Janeiro. \u201cInforma\u00e7\u00e3o e transpar\u00eancia movem o Mercado de Capitais. A CVM \u00e9 um reposit\u00f3rio de dados e indicadores. Essa an\u00e1lise tende a ser um exerc\u00edcio interessante que a Associa\u00e7\u00e3o Comercial pode fazer e que a CVM pode apoiar\u201d, afirmou.<\/p>\n\n\n\n<p>Parceria aceita, o presidente Josier Vilar prop\u00f4s a assinatura de um termo de compromisso com a CVM para definir um trabalho em parceria. \u201c\u00c9 importante ter acesso a esses dados para que possamos trabalhar essas informa\u00e7\u00f5es e disponibilizar para nossos associados\u201d, disse.<\/p>\n\n\n\n<p>A pr\u00f3xima reuni\u00e3o do Conselho est\u00e1 agendada para o dia 22 de agosto, \u00e0s 11 horas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa-1024x461.jpg\" alt=\"\" class=\"wp-image-29395\" style=\"width:360px\" srcset=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa-1024x461.jpg 1024w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa-300x135.jpg 300w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa-768x346.jpg 768w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa-1536x691.jpg 1536w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa-600x270.jpg 600w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"545\" src=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1-1024x545.jpg\" alt=\"\" class=\"wp-image-29396\" style=\"width:360px\" srcset=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1-1024x545.jpg 1024w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1-300x160.jpg 300w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1-768x409.jpg 768w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1-1536x818.jpg 1536w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1-600x320.jpg 600w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa1.jpg 1690w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"461\" src=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2-1024x461.jpg\" alt=\"\" class=\"wp-image-29397\" style=\"width:360px\" srcset=\"https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2-1024x461.jpg 1024w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2-300x135.jpg 300w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2-768x346.jpg 768w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2-1536x691.jpg 1536w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2-600x270.jpg 600w, https:\/\/acrj.org.br\/wp-content\/uploads\/2024\/08\/mesa2.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>O presidente da Comiss\u00e3o de Valores Mobili\u00e1rios (CVM), Jo\u00e3o Pedro Nascimento, participou, dia 1\u00ba de agosto, de um encontro promovido pelo Conselho Empresarial do Desenvolvimento&hellip;<\/p>\n","protected":false},"author":3,"featured_media":29394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[56,10],"tags":[],"class_list":["post-29393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque_conselhos","category-noticias"],"_links":{"self":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/posts\/29393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/comments?post=29393"}],"version-history":[{"count":0,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/posts\/29393\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/media\/29394"}],"wp:attachment":[{"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/media?parent=29393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/categories?post=29393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/acrj.org.br\/index.php\/wp-json\/wp\/v2\/tags?post=29393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}